{"id":82260,"date":"2025-05-24T08:03:24","date_gmt":"2025-05-24T08:03:26","guid":{"rendered":"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/"},"modified":"2025-05-24T08:03:27","modified_gmt":"2025-05-24T08:03:27","slug":"martinez-rose-2","status":"publish","type":"product","link":"https:\/\/aral.cetrexmarketing.com\/ca\/producto\/martinez-rose-2\/","title":{"rendered":"Martinez Ros\u00e9"},"content":{"rendered":"<p><strong>Martinez Ros\u00e9<\/strong><\/p>\n<p>Cava apte per a qualsevol moment i ocasi\u00f3 per tenir una gran adaptaci\u00f3 gastron\u00f2mica. Aquesta adaptaci\u00f3 queda potenciada en aperitius, tapes, menjars lleugers, i amb una gran dosi d&#8217;eleg\u00e0ncia, amb un rigor i una cremositat molt especial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cava apte per a qualsevol moment i ocasi\u00f3 per tenir una gran adaptaci\u00f3 gastron\u00f2mica, i que queda potenciada en aperitius, tapes, menjars lleugers, i amb una gran dosi d&#8217;eleg\u00e0ncia guardant un rigor i una cremositat molt especial.<\/p>\n","protected":false},"featured_media":82258,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"pwb-brand":[32909,45522],"product_brand":[],"product_cat":[33038,33080,33282,33048],"product_tag":[48480,50379,50380,50377],"class_list":{"0":"post-82260","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-cava-d-o","7":"pwb-brand-rimarts","8":"product_cat-vi-escumos-ca","9":"product_cat-cava-ca","10":"product_cat-cava-rosat-ca","11":"product_cat-ecologic-ca","12":"product_tag-ecologic","13":"product_tag-escumos-ca","14":"product_tag-escumos-rosat-ca","15":"product_tag-sant-sadurni-danoia-ca","16":"pa_bodega-ricardmdesimon-ca","17":"pa_cantidaddeazucar-brutnature-ca","18":"pa_do-cava-d-o-ca-2","19":"pa_ecologico-vegano-natural-ecologic","20":"pa_formatoenml-750-ca","21":"pa_graduacion-11_5","22":"pa_pais-espanya-ca","23":"pa_pueblociudad-santsadurnidanoiabarcelona-ca","24":"pa_region-cataluna-ca","25":"pa_tipodevino-vinoespumoso","26":"entry","27":"has-media","29":"first","30":"instock","31":"taxable","32":"shipping-taxable","33":"purchasable","34":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.1 (Yoast SEO v23.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Martinez Ros\u00e9<\/title>\n<meta name=\"description\" content=\"Comprar en l\u00ednia a bon preu el cava Martinez Ros\u00e9 elaborat per Ricard M. de Simon a la DO Cava. Rapidesa, confian\u00e7a i seguretat defineixen la nostra vinoteca.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Martinez Ros\u00e9\" \/>\n<meta property=\"og:description\" content=\"Comprar en l\u00ednia a bon preu el cava Martinez Ros\u00e9 elaborat per Ricard M. de Simon a la DO Cava. Rapidesa, confian\u00e7a i seguretat defineixen la nostra vinoteca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00f3n La Cata\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-24T08:03:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2025\/05\/MARTINEZ-ROSE.jpg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"765\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/\",\"name\":\"Martinez Ros\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2025\/05\/MARTINEZ-ROSE.jpg.png\",\"datePublished\":\"2025-05-24T08:03:26+00:00\",\"dateModified\":\"2025-05-24T08:03:27+00:00\",\"description\":\"Comprar en l\u00ednia a bon preu el cava Martinez Ros\u00e9 elaborat per Ricard M. de Simon a la DO Cava. Rapidesa, confian\u00e7a i seguretat defineixen la nostra vinoteca.\",\"breadcrumb\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/#primaryimage\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2025\/05\/MARTINEZ-ROSE.jpg.png\",\"contentUrl\":\"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2025\/05\/MARTINEZ-ROSE.jpg.png\",\"width\":765,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aral.cetrexmarketing.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/aral.cetrexmarketing.com\/ca\/tienda-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Martinez Ros\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#website\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/\",\"name\":\"M\u00f3n La Cata\",\"description\":\"Tienda de vinos, licores, cervezas y gourmet\",\"publisher\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aral.cetrexmarketing.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#organization\",\"name\":\"M\u00f3n La Cata\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png\",\"contentUrl\":\"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png\",\"width\":1024,\"height\":409,\"caption\":\"M\u00f3n La Cata\"},\"image\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Martinez Ros\u00e9","description":"Comprar en l\u00ednia a bon preu el cava Martinez Ros\u00e9 elaborat per Ricard M. de Simon a la DO Cava. Rapidesa, confian\u00e7a i seguretat defineixen la nostra vinoteca.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ca_ES","og_type":"article","og_title":"Martinez Ros\u00e9","og_description":"Comprar en l\u00ednia a bon preu el cava Martinez Ros\u00e9 elaborat per Ricard M. de Simon a la DO Cava. Rapidesa, confian\u00e7a i seguretat defineixen la nostra vinoteca.","og_url":"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/","og_site_name":"M\u00f3n La Cata","article_modified_time":"2025-05-24T08:03:27+00:00","og_image":[{"width":765,"height":1024,"url":"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2025\/05\/MARTINEZ-ROSE.jpg.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/","url":"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/","name":"Martinez Ros\u00e9","isPartOf":{"@id":"https:\/\/aral.cetrexmarketing.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/#primaryimage"},"image":{"@id":"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/#primaryimage"},"thumbnailUrl":"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2025\/05\/MARTINEZ-ROSE.jpg.png","datePublished":"2025-05-24T08:03:26+00:00","dateModified":"2025-05-24T08:03:27+00:00","description":"Comprar en l\u00ednia a bon preu el cava Martinez Ros\u00e9 elaborat per Ricard M. de Simon a la DO Cava. Rapidesa, confian\u00e7a i seguretat defineixen la nostra vinoteca.","breadcrumb":{"@id":"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/#primaryimage","url":"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2025\/05\/MARTINEZ-ROSE.jpg.png","contentUrl":"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2025\/05\/MARTINEZ-ROSE.jpg.png","width":765,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/aral.cetrexmarketing.com\/producto\/martinez-rose-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aral.cetrexmarketing.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/aral.cetrexmarketing.com\/ca\/tienda-2\/"},{"@type":"ListItem","position":3,"name":"Martinez Ros\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/aral.cetrexmarketing.com\/#website","url":"https:\/\/aral.cetrexmarketing.com\/","name":"M\u00f3n La Cata","description":"Tienda de vinos, licores, cervezas y gourmet","publisher":{"@id":"https:\/\/aral.cetrexmarketing.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aral.cetrexmarketing.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/aral.cetrexmarketing.com\/#organization","name":"M\u00f3n La Cata","url":"https:\/\/aral.cetrexmarketing.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/","url":"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png","contentUrl":"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png","width":1024,"height":409,"caption":"M\u00f3n La Cata"},"image":{"@id":"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/"}}]}},"brands":[{"id":32909,"name":"Cava D.O.","slug":"cava-d-o"},{"id":45522,"name":"Rimarts","slug":"rimarts"}],"_links":{"self":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/product\/82260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/comments?post=82260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/media\/82258"}],"wp:attachment":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/media?parent=82260"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/pwb-brand?post=82260"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/product_brand?post=82260"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/product_cat?post=82260"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/product_tag?post=82260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}