{"id":33001,"count":10,"description":"Unos a\u00f1os antes de la fundaci\u00f3n de la ciudad de Mendoza el sacerdote espa\u00f1ol Juan Cidr\u00f3 planto la primera vi\u00f1a en Santiago del Estero, cultivo dominado por la misiones, hacia el a\u00f1o 1552, que cultivaban una cepa que existe en la actualidad y que se denomina con diferentes nombres seg\u00fan pa\u00eds: Misi\u00f3n, Criolla, etc. En general Argentina tiene en las zonas vin\u00edcolas un clima caluroso y seco, pero en este caso no hay problema ya que goza de un abastecimiento de agua, a trav\u00e9s de los canales y arroyos que vienen del deshielo de los Andes y de los numerosos acu\u00edferos.\nLos terrenos son muy variados, as\u00ed como los microclimas, de forma que no se puede hablar de una uniformidad en cuanto a vinos. Las zonas del nordeste, este y norte como Mendoza contempla la mayor producci\u00f3n de vino, pero nuevas zonas se han incorporado como es el caso de las zonas situadas al sur.","link":"https:\/\/aral.cetrexmarketing.com\/ca\/brand\/vinos-de-argentina\/","name":"Vinos de Argentina","slug":"vinos-de-argentina","taxonomy":"pwb-brand","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.1 (Yoast SEO v23.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vinos de Argentina - M\u00f3n La Cata<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vinos de Argentina archivos\" \/>\n<meta property=\"og:description\" content=\"Unos a\u00f1os antes de la fundaci\u00f3n de la ciudad de Mendoza el sacerdote espa\u00f1ol Juan Cidr\u00f3 planto la primera vi\u00f1a en Santiago del Estero, cultivo dominado por la misiones, hacia el a\u00f1o 1552, que cultivaban una cepa que existe en la actualidad y que se denomina con diferentes nombres seg\u00fan pa\u00eds: Misi\u00f3n, Criolla, etc. En general Argentina tiene en las zonas vin\u00edcolas un clima caluroso y seco, pero en este caso no hay problema ya que goza de un abastecimiento de agua, a trav\u00e9s de los canales y arroyos que vienen del deshielo de los Andes y de los numerosos acu\u00edferos. Los terrenos son muy variados, as\u00ed como los microclimas, de forma que no se puede hablar de una uniformidad en cuanto a vinos. Las zonas del nordeste, este y norte como Mendoza contempla la mayor producci\u00f3n de vino, pero nuevas zonas se han incorporado como es el caso de las zonas situadas al sur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aral.cetrexmarketing.com\/brand\/vinos-de-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00f3n La Cata\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/brand\/vinos-de-argentina\/\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/brand\/vinos-de-argentina\/\",\"name\":\"Vinos de Argentina - M\u00f3n La Cata\",\"isPartOf\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/brand\/vinos-de-argentina\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/brand\/vinos-de-argentina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aral.cetrexmarketing.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vinos de Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#website\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/\",\"name\":\"M\u00f3n La Cata\",\"description\":\"Tienda de vinos, licores, cervezas y gourmet\",\"publisher\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aral.cetrexmarketing.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#organization\",\"name\":\"M\u00f3n La Cata\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png\",\"contentUrl\":\"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png\",\"width\":1024,\"height\":409,\"caption\":\"M\u00f3n La Cata\"},\"image\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vinos de Argentina - M\u00f3n La Cata","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ca_ES","og_type":"article","og_title":"Vinos de Argentina archivos","og_description":"Unos a\u00f1os antes de la fundaci\u00f3n de la ciudad de Mendoza el sacerdote espa\u00f1ol Juan Cidr\u00f3 planto la primera vi\u00f1a en Santiago del Estero, cultivo dominado por la misiones, hacia el a\u00f1o 1552, que cultivaban una cepa que existe en la actualidad y que se denomina con diferentes nombres seg\u00fan pa\u00eds: Misi\u00f3n, Criolla, etc. En general Argentina tiene en las zonas vin\u00edcolas un clima caluroso y seco, pero en este caso no hay problema ya que goza de un abastecimiento de agua, a trav\u00e9s de los canales y arroyos que vienen del deshielo de los Andes y de los numerosos acu\u00edferos. Los terrenos son muy variados, as\u00ed como los microclimas, de forma que no se puede hablar de una uniformidad en cuanto a vinos. Las zonas del nordeste, este y norte como Mendoza contempla la mayor producci\u00f3n de vino, pero nuevas zonas se han incorporado como es el caso de las zonas situadas al sur.","og_url":"https:\/\/aral.cetrexmarketing.com\/brand\/vinos-de-argentina\/","og_site_name":"M\u00f3n La Cata","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aral.cetrexmarketing.com\/brand\/vinos-de-argentina\/","url":"https:\/\/aral.cetrexmarketing.com\/brand\/vinos-de-argentina\/","name":"Vinos de Argentina - M\u00f3n La Cata","isPartOf":{"@id":"https:\/\/aral.cetrexmarketing.com\/#website"},"breadcrumb":{"@id":"https:\/\/aral.cetrexmarketing.com\/brand\/vinos-de-argentina\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/aral.cetrexmarketing.com\/brand\/vinos-de-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aral.cetrexmarketing.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Vinos de Argentina"}]},{"@type":"WebSite","@id":"https:\/\/aral.cetrexmarketing.com\/#website","url":"https:\/\/aral.cetrexmarketing.com\/","name":"M\u00f3n La Cata","description":"Tienda de vinos, licores, cervezas y gourmet","publisher":{"@id":"https:\/\/aral.cetrexmarketing.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aral.cetrexmarketing.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/aral.cetrexmarketing.com\/#organization","name":"M\u00f3n La Cata","url":"https:\/\/aral.cetrexmarketing.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/","url":"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png","contentUrl":"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png","width":1024,"height":409,"caption":"M\u00f3n La Cata"},"image":{"@id":"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/pwb-brand\/33001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/pwb-brand"}],"about":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/taxonomies\/pwb-brand"}],"wp:post_type":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/product?pwb-brand=33001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}