{"id":45009,"count":2,"description":"","link":"https:\/\/aral.cetrexmarketing.com\/ca\/brand\/arnaiz\/","name":"Arnaiz","slug":"arnaiz","taxonomy":"pwb-brand","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.1 (Yoast SEO v23.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arnaiz - M\u00f3n La Cata<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arnaiz archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aral.cetrexmarketing.com\/brand\/arnaiz\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00f3n La Cata\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/brand\/arnaiz\/\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/brand\/arnaiz\/\",\"name\":\"Arnaiz - M\u00f3n La Cata\",\"isPartOf\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/brand\/arnaiz\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/brand\/arnaiz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aral.cetrexmarketing.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arnaiz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#website\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/\",\"name\":\"M\u00f3n La Cata\",\"description\":\"Tienda de vinos, licores, cervezas y gourmet\",\"publisher\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aral.cetrexmarketing.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#organization\",\"name\":\"M\u00f3n La Cata\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png\",\"contentUrl\":\"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png\",\"width\":1024,\"height\":409,\"caption\":\"M\u00f3n La Cata\"},\"image\":{\"@id\":\"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arnaiz - M\u00f3n La Cata","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ca_ES","og_type":"article","og_title":"Arnaiz archivos","og_url":"https:\/\/aral.cetrexmarketing.com\/brand\/arnaiz\/","og_site_name":"M\u00f3n La Cata","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aral.cetrexmarketing.com\/brand\/arnaiz\/","url":"https:\/\/aral.cetrexmarketing.com\/brand\/arnaiz\/","name":"Arnaiz - M\u00f3n La Cata","isPartOf":{"@id":"https:\/\/aral.cetrexmarketing.com\/#website"},"breadcrumb":{"@id":"https:\/\/aral.cetrexmarketing.com\/brand\/arnaiz\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/aral.cetrexmarketing.com\/brand\/arnaiz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aral.cetrexmarketing.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Arnaiz"}]},{"@type":"WebSite","@id":"https:\/\/aral.cetrexmarketing.com\/#website","url":"https:\/\/aral.cetrexmarketing.com\/","name":"M\u00f3n La Cata","description":"Tienda de vinos, licores, cervezas y gourmet","publisher":{"@id":"https:\/\/aral.cetrexmarketing.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aral.cetrexmarketing.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/aral.cetrexmarketing.com\/#organization","name":"M\u00f3n La Cata","url":"https:\/\/aral.cetrexmarketing.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/","url":"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png","contentUrl":"https:\/\/aral.cetrexmarketing.com\/wp-content\/uploads\/2024\/10\/aral-logo-neg-1024x409-1.png","width":1024,"height":409,"caption":"M\u00f3n La Cata"},"image":{"@id":"https:\/\/aral.cetrexmarketing.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/pwb-brand\/45009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/pwb-brand"}],"about":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/taxonomies\/pwb-brand"}],"wp:post_type":[{"href":"https:\/\/aral.cetrexmarketing.com\/ca\/wp-json\/wp\/v2\/product?pwb-brand=45009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}